{"id":22,"count":57,"description":"","link":"https:\/\/beraucoalenergy.co.id\/category\/financial-report\/","name":"Financial Report","slug":"financial-report","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories\/22"}],"collection":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts?categories=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}