{"id":28,"count":335,"description":"","link":"https:\/\/beraucoalenergy.co.id\/category\/post-halaman-depan\/","name":"post halaman depan","slug":"post-halaman-depan","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories\/28"}],"collection":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}