{"id":3098,"date":"2015-02-08T12:18:40","date_gmt":"2015-02-08T12:18:40","guid":{"rendered":"http:\/\/www.beraucoalenergy.co.id\/?p=3098"},"modified":"2015-02-08T12:18:40","modified_gmt":"2015-02-08T12:18:40","slug":"media-3","status":"publish","type":"post","link":"https:\/\/beraucoalenergy.co.id\/2015\/02\/08\/media-3\/","title":{"rendered":"media 3"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":3054,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[],"_links":{"self":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/3098"}],"collection":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/comments?post=3098"}],"version-history":[{"count":1,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/3098\/revisions"}],"predecessor-version":[{"id":3099,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/3098\/revisions\/3099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/media\/3054"}],"wp:attachment":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/media?parent=3098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories?post=3098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/tags?post=3098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}