{"id":3100,"date":"2015-02-08T12:19:55","date_gmt":"2015-02-08T12:19:55","guid":{"rendered":"http:\/\/www.beraucoalenergy.co.id\/?p=3100"},"modified":"2015-02-08T12:19:55","modified_gmt":"2015-02-08T12:19:55","slug":"media-2","status":"publish","type":"post","link":"https:\/\/beraucoalenergy.co.id\/2015\/02\/08\/media-2\/","title":{"rendered":"media 2"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":3053,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[24],"tags":[25],"_links":{"self":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/3100"}],"collection":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/comments?post=3100"}],"version-history":[{"count":1,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/3100\/revisions"}],"predecessor-version":[{"id":3101,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/3100\/revisions\/3101"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/media\/3053"}],"wp:attachment":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/media?parent=3100"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories?post=3100"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/tags?post=3100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}