{"id":7926,"date":"2024-05-16T02:54:00","date_gmt":"2024-05-15T18:54:00","guid":{"rendered":"https:\/\/beraucoalenergy.co.id\/?p=7926"},"modified":"2024-05-16T17:56:38","modified_gmt":"2024-05-16T09:56:38","slug":"surat-pernyataan-pemegang-saham-independen-independent-shareholder-statement","status":"publish","type":"post","link":"https:\/\/beraucoalenergy.co.id\/2024\/05\/16\/surat-pernyataan-pemegang-saham-independen-independent-shareholder-statement\/","title":{"rendered":"SURAT PERNYATAAN PEMEGANG SAHAM INDEPENDEN (INDEPENDENT SHAREHOLDER STATEMENT)"},"content":{"rendered":"\n<p><a href=\"https:\/\/drive.google.com\/open?id=1F10U10ViyichHb8A9-chjLoL0xuOos47&amp;usp=drive_fs\">Surat Pernyataan Pemegang Saham Independen (Independent Shareholder Statement)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Surat Pernyataan Pemegang Saham Independen (Independent Shareholder Statement)<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[18,3,32,28],"tags":[],"_links":{"self":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/7926"}],"collection":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/comments?post=7926"}],"version-history":[{"count":1,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/7926\/revisions"}],"predecessor-version":[{"id":7927,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/7926\/revisions\/7927"}],"wp:attachment":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/media?parent=7926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories?post=7926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/tags?post=7926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}