{"id":8694,"date":"2026-05-11T09:21:00","date_gmt":"2026-05-11T01:21:00","guid":{"rendered":"https:\/\/beraucoalenergy.co.id\/?p=8694"},"modified":"2026-05-11T16:29:00","modified_gmt":"2026-05-11T08:29:00","slug":"pengumuman-rupst-dan-rupslb-11-mei-2026","status":"publish","type":"post","link":"https:\/\/beraucoalenergy.co.id\/2026\/05\/11\/pengumuman-rupst-dan-rupslb-11-mei-2026\/","title":{"rendered":"Pengumuman RUPST dan RUPSLB &#8211; 11 Mei 2026"},"content":{"rendered":"\n<ul><li><a href=\"https:\/\/drive.google.com\/file\/d\/1gISBZ8nyaCFPCLavFTvzwAQ77rYfFgl-\/view?usp=sharing\">Pengumuman RUPST dan RUPSLB<\/a><\/li><li><a href=\"https:\/\/drive.google.com\/file\/d\/1iX27p53AAbbl3T0XePuWCxwtzmZ2je4V\/view?usp=sharing\">AGMS dan EGMS Announcement 2026<\/a><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pengumuman RUPST dan RUPSLB AGMS dan EGMS Announcement 2026<\/p>\n","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[18,48,49,22,19,27,24,3,32,28],"tags":[],"_links":{"self":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/8694"}],"collection":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/comments?post=8694"}],"version-history":[{"count":1,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/8694\/revisions"}],"predecessor-version":[{"id":8695,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/posts\/8694\/revisions\/8695"}],"wp:attachment":[{"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/media?parent=8694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/categories?post=8694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beraucoalenergy.co.id\/wp-json\/wp\/v2\/tags?post=8694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}